{"id":30286,"date":"2019-01-28T19:58:17","date_gmt":"2019-01-28T18:58:17","guid":{"rendered":"https:\/\/cardiofirstangel.fr\/primer-angel-cardio-y-deporte\/"},"modified":"2024-11-19T15:04:24","modified_gmt":"2024-11-19T14:04:24","slug":"primer-angel-cardio-y-deporte","status":"publish","type":"post","link":"https:\/\/cardiofirstangel.fr\/es\/primer-angel-cardio-y-deporte\/","title":{"rendered":"Cardio First Angel y deporte"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb4px||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb1px|auto||auto||\u00bb custom_padding=\u00bb6px||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb32px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1 style=\"text-align: left\"><strong>Cardio First Angel y deporte <\/strong><\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.16&#8243; text_font=\u00bbLato||||||||\u00bb text_font_size=\u00bb16px\u00bb text_line_height=\u00bb1.9em\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb text_orientation=\u00bbjustified\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Nuestro objetivo es proteger a los clubes deportivos y sensibilizar a los deportistas. El 60-80% de los deportistas no presentan s\u00edntomas antes de sufrir una parada cardiaca. Un gran n\u00famero de accidentes card\u00edacos pueden producirse tras un ejercicio intenso que somete al coraz\u00f3n a una gran tensi\u00f3n. Un estudio italiano de 2017 descubri\u00f3 que los deportistas ten\u00edan tres veces m\u00e1s probabilidades de morir de muerte s\u00fabita que la poblaci\u00f3n general. Este riesgo puede dividirse por 4 si las personas presentes en el momento del incidente tienen acceso a primeros auxilios.  <\/p>\n<p>El Cardio First Angel permite a cualquier persona, con o sin formaci\u00f3n, realizar un masaje cardiaco eficaz mientras espera a que llegue la ayuda o incluso un DEA. Adem\u00e1s, gracias a su peque\u00f1o tama\u00f1o, cabe f\u00e1cilmente en una bolsa de deporte o incluso se puede colgar en la recepci\u00f3n, en los vestuarios o incluso en los campos de deporte.<\/p>\n<p>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.cardiofirstangel.fr\/\/wp-content\/uploads\/sites\/15653\/2019\/01\/Image-1.jpg\u00bb title_text=\u00bbImagen-1&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb61%\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb68%\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Se trata del <span>Cardio <\/span><span>First <\/span><span>Angel<\/span> en el CNE (Centro Nacional de Entrenamiento) de la Federaci\u00f3n Francesa de Tenis.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cardio First Angel y deporte Nuestro objetivo es proteger a los clubes deportivos y sensibilizar a los deportistas. El 60-80% de los deportistas no presentan s\u00edntomas antes de sufrir una parada cardiaca. Un gran n\u00famero de accidentes card\u00edacos pueden producirse tras un ejercicio intenso que somete al coraz\u00f3n a una gran tensi\u00f3n. Un estudio italiano [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","content-type":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[67],"tags":[],"class_list":["post-30286","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cardiofirstangel.fr\/es\/wp-json\/wp\/v2\/posts\/30286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cardiofirstangel.fr\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cardiofirstangel.fr\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cardiofirstangel.fr\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cardiofirstangel.fr\/es\/wp-json\/wp\/v2\/comments?post=30286"}],"version-history":[{"count":16,"href":"https:\/\/cardiofirstangel.fr\/es\/wp-json\/wp\/v2\/posts\/30286\/revisions"}],"predecessor-version":[{"id":30987,"href":"https:\/\/cardiofirstangel.fr\/es\/wp-json\/wp\/v2\/posts\/30286\/revisions\/30987"}],"wp:attachment":[{"href":"https:\/\/cardiofirstangel.fr\/es\/wp-json\/wp\/v2\/media?parent=30286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cardiofirstangel.fr\/es\/wp-json\/wp\/v2\/categories?post=30286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cardiofirstangel.fr\/es\/wp-json\/wp\/v2\/tags?post=30286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}